<link rel="stylesheet" href="https://use.fontawesome.com/releases/v5.5.0/css/all.css" integrity="sha384-B4dIYHKNBt8Bc12p+WXckhzcICo0wtJAoU8YZTY5qE0Id1GSseTk6S+L3BlXeVIU" crossorigin="anonymous">
{"id":7660,"date":"2024-04-05T14:33:42","date_gmt":"2024-04-05T14:33:42","guid":{"rendered":"https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/?page_id=7660"},"modified":"2024-04-05T16:51:27","modified_gmt":"2024-04-05T16:51:27","slug":"a-continue","status":"publish","type":"page","link":"https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/a-continue\/","title":{"rendered":"De simples moyens d\u2019honorer le Jour de la Terre en avril et tout au long de l&rsquo;ann\u00e9e (suite)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7660\" class=\"elementor elementor-7660\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-96efe8d header_title banner_img elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"96efe8d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-76f7561\" data-id=\"76f7561\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d9a853a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d9a853a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68d9c5a page_contain\" data-id=\"68d9c5a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50f1f9b elementor-widget elementor-widget-image\" data-id=\"50f1f9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1366\" height=\"768\" src=\"https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-content\/uploads\/sites\/217\/2024\/04\/03_138411_6_LAND.jpg\" class=\"attachment-full size-full wp-image-7644\" alt=\"\" srcset=\"https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-content\/uploads\/sites\/217\/2024\/04\/03_138411_6_LAND.jpg 1366w, https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-content\/uploads\/sites\/217\/2024\/04\/03_138411_6_LAND-300x169.jpg 300w, https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-content\/uploads\/sites\/217\/2024\/04\/03_138411_6_LAND-1024x576.jpg 1024w, https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-content\/uploads\/sites\/217\/2024\/04\/03_138411_6_LAND-768x432.jpg 768w\" sizes=\"(max-width: 1366px) 100vw, 1366px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">canada.ca\/v\u00e9hiculesmoyensetlourdsz\u00e9ro\u00e9mission<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bab7219 mobile_pera elementor-widget elementor-widget-text-editor\" data-id=\"bab7219\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Des v\u00e9hicules utilitaires encore plus verts<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0a0a3b mobile_pera elementor-widget elementor-widget-text-editor\" data-id=\"d0a0a3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Beaucoup d\u2019entre nous doivent utiliser une voiture ou un camion au quotidien. Si tel est votre cas, pensez \u00e0 vous renseigner sur les v\u00e9hicules \u00e9lectriques (VE). Les VE r\u00e9duisent consid\u00e9rablement les \u00e9missions et peuvent vous faire \u00e9conomiser de l\u2019argent sur l\u2019essence et l\u2019entretien. De plus, des mesures incitatives gouvernementales peuvent aider \u00e0 r\u00e9duire le co\u00fbt de l\u2019achat ou de la location. L\u2019un de ces programmes incitatifs est sp\u00e9cialement con\u00e7u pour les entreprises et les organisations qui investissent dans des v\u00e9hicules utilitaires moyens et lourds \u00e9lectriques, qui peuvent aider la plan\u00e8te.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-198c870 elementor-widget elementor-widget-advertisement\" data-id=\"198c870\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"advertisement.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ads-align-center\"><div id='div-gpt-ad-1647217249799-0' style='min-width: 300px; min-height: 250px;'>\r\n  <script>\r\n    googletag.cmd.push(function() { googletag.display('div-gpt-ad-1647217249799-0'); });\r\n  <\/script>\r\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b6ad93 mobile_pera elementor-widget elementor-widget-text-editor\" data-id=\"0b6ad93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Faites votre m\u00e9nage\u00a0<\/b><b>du printemps de\u00a0<\/b><b>mani\u00e8re durable<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74263c8 mobile_pera elementor-widget elementor-widget-text-editor\" data-id=\"74263c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>C\u2019est une p\u00e9riode de l\u2019ann\u00e9e o\u00f9 beaucoup d\u2019entre nous entreprennent de rafra\u00eechir leur maison. Et, selon un r\u00e9cent sondage r\u00e9alis\u00e9 par les Aliments Maple Leaf, 95 % des Canadiens se soucient de la protection de l\u2019environnement. R\u00e9fl\u00e9chissez donc \u00e0 la mani\u00e8re dont vous pouvez rendre votre processus de nettoyage plus durable. Vous pouvez r\u00e9organiser votre r\u00e9frig\u00e9rateur pour que les aliments se conservent plus longtemps, ou magasiner dans votre propre garde-robe pour trouver de nouveaux styles au lieu de vous r\u00e9approvisionner en produits de la mode rapide.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-758cf82 elementor-widget elementor-widget-advertisement\" data-id=\"758cf82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"advertisement.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ads-align-center\"><div id='div-gpt-ad-1648595513425-0' style='min-width: 300px; min-height: 250px;'>\r\n  <script>\r\n    googletag.cmd.push(function() { googletag.display('div-gpt-ad-1648595513425-0'); });\r\n  <\/script>\r\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55fbd9b elementor-widget elementor-widget-image\" data-id=\"55fbd9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1366\" height=\"768\" src=\"https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-content\/uploads\/sites\/217\/2024\/04\/03_138411_7_LAND.jpg\" class=\"attachment-full size-full wp-image-7643\" alt=\"\" srcset=\"https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-content\/uploads\/sites\/217\/2024\/04\/03_138411_7_LAND.jpg 1366w, https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-content\/uploads\/sites\/217\/2024\/04\/03_138411_7_LAND-300x169.jpg 300w, https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-content\/uploads\/sites\/217\/2024\/04\/03_138411_7_LAND-1024x576.jpg 1024w, https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-content\/uploads\/sites\/217\/2024\/04\/03_138411_7_LAND-768x432.jpg 768w\" sizes=\"(max-width: 1366px) 100vw, 1366px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">mapleleaffoods.com\/fr\/nos-engagements<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91af55e mobile_pera elementor-widget elementor-widget-text-editor\" data-id=\"91af55e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Cultivez votre\u00a0<\/b><b>propre potager<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0aba34 mobile_pera elementor-widget elementor-widget-text-editor\" data-id=\"b0aba34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le Jour de la Terre peut servir d\u2019inspiration pour renouer avec la nature. Faites un projet de bricolage durable, comme une jardini\u00e8re simple pour votre cour ou votre balcon. Vous pourrez ainsi cultiver vos propres fines herbes, fruits et l\u00e9gumes ou fleurs et en faire profiter votre famille. Votre quincaillerie locale pourrait aussi avoir des guides pratiques en ligne pour vous aider.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9ea614 mobile_pera elementor-widget elementor-widget-text-editor\" data-id=\"d9ea614\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>www.leditionnouvelles.com<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>canada.ca\/v\u00e9hiculesmoyensetlourdsz\u00e9ro\u00e9mission Des v\u00e9hicules utilitaires encore plus verts Beaucoup d\u2019entre nous doivent utiliser une voiture ou un camion au quotidien. Si tel est votre cas, pensez \u00e0 vous renseigner sur les v\u00e9hicules \u00e9lectriques (VE). Les VE r\u00e9duisent consid\u00e9rablement les \u00e9missions et peuvent vous faire \u00e9conomiser de l\u2019argent sur l\u2019essence et l\u2019entretien. De plus, des mesures incitatives [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"page-categories":[],"class_list":["post-7660","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-json\/wp\/v2\/pages\/7660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-json\/wp\/v2\/comments?post=7660"}],"version-history":[{"count":9,"href":"https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-json\/wp\/v2\/pages\/7660\/revisions"}],"predecessor-version":[{"id":7698,"href":"https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-json\/wp\/v2\/pages\/7660\/revisions\/7698"}],"wp:attachment":[{"href":"https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-json\/wp\/v2\/media?parent=7660"}],"wp:term":[{"taxonomy":"page-categories","embeddable":true,"href":"https:\/\/kiosque.acadienouvelle.com\/jour-terre-2024\/wp-json\/wp\/v2\/page-categories?post=7660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}